{"id":2877,"date":"2026-03-24T10:42:15","date_gmt":"2026-03-24T10:42:15","guid":{"rendered":"https:\/\/www.fondazioneinvernizzi.it\/?p=2877"},"modified":"2026-03-25T16:13:43","modified_gmt":"2026-03-25T16:13:43","slug":"dalla-disinformazione-alla-fiducia-come-comunicare-scienza-e-agro-food-in-modo-efficace","status":"publish","type":"post","link":"https:\/\/www.fondazioneinvernizzi.it\/en\/2026\/03\/24\/dalla-disinformazione-alla-fiducia-come-comunicare-scienza-e-agro-food-in-modo-efficace\/","title":{"rendered":"Dalla disinformazione alla fiducia: come comunicare scienza e agro-food"},"content":{"rendered":"<h1 class=\"wp-block-heading\">Dalla disinformazione alla fiducia: come comunicare scienza e agro-food <\/h1>\n\n\n\n<p class=\"has-medium-font-size\"><strong>24 marzo 2026<\/strong> &#8211; Strategie e sfide della comunicazione scientifica nel settore agro-alimentare<\/p>\n\n\n\n<div style=\"height:60px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-media-text is-stacked-on-mobile is-vertically-aligned-top\" style=\"grid-template-columns:48% auto\"><figure class=\"wp-block-media-text__media\"><img loading=\"lazy\" decoding=\"async\" width=\"852\" height=\"1024\" src=\"https:\/\/www.fondazioneinvernizzi.it\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-25-at-17.04.56-852x1024.jpeg\" alt=\"\" class=\"wp-image-2944 size-full\" srcset=\"https:\/\/www.fondazioneinvernizzi.it\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-25-at-17.04.56-852x1024.jpeg 852w, https:\/\/www.fondazioneinvernizzi.it\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-25-at-17.04.56-250x300.jpeg 250w, https:\/\/www.fondazioneinvernizzi.it\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-25-at-17.04.56-768x923.jpeg 768w, https:\/\/www.fondazioneinvernizzi.it\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-25-at-17.04.56-1279x1536.jpeg 1279w, https:\/\/www.fondazioneinvernizzi.it\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-25-at-17.04.56-10x12.jpeg 10w, https:\/\/www.fondazioneinvernizzi.it\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-25-at-17.04.56.jpeg 1332w\" sizes=\"auto, (max-width: 852px) 100vw, 852px\" \/><\/figure><div class=\"wp-block-media-text__content\">\n<p><strong>Marted\u00ec 24 marzo alle ore 16.30<\/strong>, Fondazione Invernizzi ha promosso un incontro dedicato al ruolo della <strong>comunicazione scientifica nel settore agro-alimentare<\/strong>, con particolare attenzione alle sfide poste dalla disinformazione e dalle fake news. L\u2019evento, organizzato in collaborazione con il <strong>Prof. Paolo Ajmone Marsan<\/strong>, docente presso l&#8217;Universit\u00e0 Cattolica del Sacro Cuore, ha rappresentato un momento di confronto tra accademia, ricerca e divulgazione, coinvolgendo esperti di comunicazione, scienza e psicologia del consumo.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n<\/div><\/div>\n\n\n\n<div style=\"height:45px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h3 class=\"wp-block-heading\">PROGRAMMA<\/h3>\n\n\n\n<p>Dopo i saluti istituzionali, un momento particolare \u00e8 stato dedicato alla premiazione dei cinque dottorandi del <strong>Dottorato Agrisystem dell\u2019Universit\u00e0 Cattolica del Sacro Cuore<\/strong>, vincitori delle Borse di Studio del Progetto <em>Portus<\/em>, finanziato dalla Fondazione Invernizzi.<\/p>\n\n\n\n<p>Il cuore dell\u2019incontro si \u00e8 articolato in <strong>tre sessioni tematiche<\/strong>, ciascuna dedicata a un aspetto chiave della comunicazione nel mondo agro-food:<\/p>\n\n\n\n<p><strong>Intervento 1: La comunicazione nel mondo Agro-Food<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Comunicazione efficace e fallita su latte, carne, benessere animale, sostenibilit\u00e0 \u2013 <strong>Relatore Dott. Alessandro Fantini<\/strong>,<strong> <\/strong>Direttore di Ruminantia<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Presentazione di progetti IRCAF e casi concreti di comunicazione nel settore del latte \u2013 <strong>Relatore Prof. Erminio Trevisi<\/strong>, Direttore IRCAF<\/li>\n<\/ul>\n\n\n\n<p><strong>Intervento 2: La divulgazione scientifica nell\u2019era delle fake news<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Come si racconta una storia scientifica \u2013 <strong>Relatore Dott. Marco Cattaneo<\/strong>,<strong> <\/strong>Direttore di Le Scienze e National Geographic<\/li>\n<\/ul>\n\n\n\n<p><strong>Intervento 3: Comunicazione e percezione del consumatore<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Organizzazione del Team, tecniche di comunicazione e percezione dei consumatori \u2013 <strong>Relatore Dott. Michele Paleologo<\/strong>, Psicologo e Docente Psicologia applicata, UNICATT<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Fake news nella divulgazione scientifica \u2013 risultati del brainstorming nell\u2019attivit\u00e0 di ricerca e lesson learned \u2013 <strong>Relatore Dott.ssa Carlotta Lomeo<\/strong>,<strong> <\/strong>dottoranda del dottorato Agrisystem, UNICATT<\/li>\n<\/ul>\n\n\n\n<p><\/p>\n\n\n\n<p>Un appuntamento pensato per approfondire come comunicare correttamente la scienza agro-alimentare, rafforzare il rapporto di fiducia con i cittadini e contrastare la diffusione di informazioni fuorvianti.<\/p>\n\n\n\n<div style=\"height:43px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n<style id=\"wp_carousel_dynamic_css2927\">#sp-wp-carousel-free-id-2927.sp-wpcp-2927 .wpcp-single-item {border: 1px none #dddddd;}#sp-wp-carousel-free-id-2927.sp-wpcp-2927 .swiper-button-prev,#sp-wp-carousel-free-id-2927.sp-wpcp-2927 .swiper-button-next,#sp-wp-carousel-free-id-2927.sp-wpcp-2927 .swiper-button-prev:hover,#sp-wp-carousel-free-id-2927.sp-wpcp-2927 .swiper-button-next:hover {background: none;border: none;font-size: 30px;}#sp-wp-carousel-free-id-2927.sp-wpcp-2927 .swiper-button-prev i,#sp-wp-carousel-free-id-2927.sp-wpcp-2927 .swiper-button-next i {color: #aaa;}#sp-wp-carousel-free-id-2927.sp-wpcp-2927 .swiper-button-prev i:hover,#sp-wp-carousel-free-id-2927.sp-wpcp-2927 .swiper-button-next i:hover {color: #178087;}#sp-wp-carousel-free-id-2927.sp-wpcp-2927 .wpcp-swiper-dots .swiper-pagination-bullet {background-color: #cccccc;}#sp-wp-carousel-free-id-2927.sp-wpcp-2927 .wpcp-swiper-dots .swiper-pagination-bullet.swiper-pagination-bullet-active {background-color: #178087;}#sp-wp-carousel-free-id-2927 .wpcpro-row>[class*=\"wpcpro-col-\"] { padding: 0 10px; padding-bottom: 20px;}@media (min-width: 480px) { .wpcpro-row .wpcpro-col-sm-1 { flex: 0 0 100%; max-width: 100%; } .wpcpro-row .wpcpro-col-sm-2 { flex: 0 0 50%; max-width: 50%; } .wpcpro-row .wpcpro-col-sm-2-5 { flex: 0 0 75%; max-width: 75%; } .wpcpro-row .wpcpro-col-sm-3 { flex: 0 0 33.333%; max-width: 33.333%; } .wpcpro-row .wpcpro-col-sm-4 { flex: 0 0 25%; max-width: 25%; } .wpcpro-row .wpcpro-col-sm-5 { flex: 0 0 20%; max-width: 20%; } .wpcpro-row .wpcpro-col-sm-6 { flex: 0 0 16.66666666666667%; max-width: 16.66666666666667%; } .wpcpro-row .wpcpro-col-sm-7 { flex: 0 0 14.28571428%; max-width: 14.28571428%; } .wpcpro-row .wpcpro-col-sm-8 { flex: 0 0 12.5%; max-width: 12.5%; } } @media (max-width: 480px) { .wpcpro-row .wpcpro-col-xs-1 { flex: 0 0 100%; max-width: 100%; } .wpcpro-row .wpcpro-col-xs-2 { flex: 0 0 50%; max-width: 50%; } .wpcpro-row .wpcpro-col-xs-3 { flex: 0 0 33.222%; max-width: 33.222%; } .wpcpro-row .wpcpro-col-xs-4 { flex: 0 0 25%; max-width: 25%; } .wpcpro-row .wpcpro-col-xs-5 { flex: 0 0 20%; max-width: 20%; } .wpcpro-row .wpcpro-col-xs-6 { flex: 0 0 16.6667%; max-width: 16.6667%; } .wpcpro-row .wpcpro-col-xs-7 { flex: 0 0 14.28571428%; max-width: 14.28571428%; } .wpcpro-row .wpcpro-col-xs-8 { flex: 0 0 12.5%; max-width: 12.5%; } } @media (min-width: 736px) { .wpcpro-row .wpcpro-col-md-1 { flex: 0 0 100%; max-width: 100%; } .wpcpro-row .wpcpro-col-md-2 { flex: 0 0 50%; max-width: 50%; } .wpcpro-row .wpcpro-col-md-2-5 { flex: 0 0 75%; max-width: 75%; } .wpcpro-row .wpcpro-col-md-3 { flex: 0 0 33.333%; max-width: 33.333%; } .wpcpro-row .wpcpro-col-md-4 { flex: 0 0 25%; max-width: 25%; } .wpcpro-row .wpcpro-col-md-5 { flex: 0 0 20%; max-width: 20%; } .wpcpro-row .wpcpro-col-md-6 { flex: 0 0 16.66666666666667%; max-width: 16.66666666666667%; } .wpcpro-row .wpcpro-col-md-7 { flex: 0 0 14.28571428%; max-width: 14.28571428%; } .wpcpro-row .wpcpro-col-md-8 { flex: 0 0 12.5%; max-width: 12.5%; } } @media (min-width: 980px) { .wpcpro-row .wpcpro-col-lg-1 { flex: 0 0 100%; max-width: 100%; } .wpcpro-row .wpcpro-col-lg-2 { flex: 0 0 50%; max-width: 50%; } .wpcpro-row .wpcpro-col-lg-3 { flex: 0 0 33.222%; max-width: 33.222%; } .wpcpro-row .wpcpro-col-lg-4 { flex: 0 0 25%; max-width: 25%; } .wpcpro-row .wpcpro-col-lg-5 { flex: 0 0 20%; max-width: 20%; } .wpcpro-row .wpcpro-col-lg-6 { flex: 0 0 16.6667%; max-width: 16.6667%; } .wpcpro-row .wpcpro-col-lg-7 { flex: 0 0 14.28571428%; max-width: 14.28571428%; } .wpcpro-row .wpcpro-col-lg-8 { flex: 0 0 12.5%; max-width: 12.5%; } } @media (min-width: 1200px) { .wpcpro-row .wpcpro-col-xl-1 { flex: 0 0 100%; max-width: 100%; } .wpcpro-row .wpcpro-col-xl-2 { flex: 0 0 50%; max-width: 50%; } .wpcpro-row .wpcpro-col-xl-3 { flex: 0 0 33.22222222%; max-width: 33.22222222%; } .wpcpro-row .wpcpro-col-xl-4 { flex: 0 0 25%; max-width: 25%; } .wpcpro-row .wpcpro-col-xl-5 { flex: 0 0 20%; max-width: 20%; } .wpcpro-row .wpcpro-col-xl-6 { flex: 0 0 16.66667%; max-width: 16.66667%; } .wpcpro-row .wpcpro-col-xl-7 { flex: 0 0 14.28571428%; max-width: 14.28571428%; } .wpcpro-row .wpcpro-col-xl-8 { flex: 0 0 12.5%; max-width: 12.5%; } }<\/style><div class=\"wpcp-carousel-wrapper wpcp-wrapper-2927\">\n\t<div id=\"wpcp-preloader-2927\" class=\"wpcp-carousel-preloader\"><img decoding=\"async\" src=\"https:\/\/www.fondazioneinvernizzi.it\/wp-content\/plugins\/wp-carousel-free\/public\/css\/spinner.svg\" alt=\"Preloader Image\" \/><\/div>\t<div class=\"wpcp-carousel-content-wrapper\">\n\t<div id=\"sp-wp-carousel-free-id-2927\" class=\"wpcp-carousel-section sp-wpcp-2927  nav-vertical-center wpcp-image-carousel wpcp-preloader wpcp-standard\" data-swiper='{ &quot;accessibility&quot;:true, &quot;spaceBetween&quot;:20, &quot;arrows&quot;:true, &quot;freeMode&quot;: false, &quot;autoplay&quot;:true, &quot;autoplaySpeed&quot;:3000, &quot;dots&quot;:true, &quot;infinite&quot;:true, &quot;speed&quot;:600, &quot;pauseOnHover&quot;:true,\t\t\t&quot;slidesToShow&quot;:{&quot;lg_desktop&quot;:3, &quot;desktop&quot;: 3, &quot;laptop&quot;: 3, &quot;tablet&quot;: 2, &quot;mobile&quot;: 1}, &quot;responsive&quot;:{&quot;desktop&quot;:1200, &quot;laptop&quot;: 980, &quot;tablet&quot;: 736, &quot;mobile&quot;: 480}, &quot;rtl&quot;:false, &quot;lazyLoad&quot;: &quot;false&quot;, &quot;swipe&quot;: true, &quot;draggable&quot;: true, &quot;swipeToSlide&quot;:false }' dir=\"ltr\">\n\t\t<div class=\"swiper-wrapper\">\n\t\t<div class=\"swiper-slide\">\n\t<div class=\"wpcp-single-item\">\n\t\t\t<a class=\"wcp-light-box\" data-buttons='[\"close\"]' data-wpc_url='https:\/\/www.fondazioneinvernizzi.it\/wp-content\/uploads\/2026\/03\/198-1536x1090.png' href=\"https:\/\/www.fondazioneinvernizzi.it\/wp-content\/uploads\/2026\/03\/198-1536x1090.png\" data-fancybox=\"wpcp_view\">\n\t\t<figure>\n\t\t\t<img loading=\"lazy\" decoding=\"async\" class=\"skip-lazy\" src=\"https:\/\/www.fondazioneinvernizzi.it\/wp-content\/uploads\/2026\/03\/198-1536x1090.png\" alt=\"198\" width=\"1536\" height=\"1090\">\t\t<\/figure>\n\t<\/a>\n\t\t<\/div>\n<\/div>\n\t<div class=\"swiper-slide\">\n\t<div class=\"wpcp-single-item\">\n\t\t\t<a class=\"wcp-light-box\" data-buttons='[\"close\"]' data-wpc_url='https:\/\/www.fondazioneinvernizzi.it\/wp-content\/uploads\/2026\/03\/199-1536x1090.png' href=\"https:\/\/www.fondazioneinvernizzi.it\/wp-content\/uploads\/2026\/03\/199-1536x1090.png\" data-fancybox=\"wpcp_view\">\n\t\t<figure>\n\t\t\t<img loading=\"lazy\" decoding=\"async\" class=\"skip-lazy\" src=\"https:\/\/www.fondazioneinvernizzi.it\/wp-content\/uploads\/2026\/03\/199-1536x1090.png\" alt=\"199\" width=\"1536\" height=\"1090\">\t\t<\/figure>\n\t<\/a>\n\t\t<\/div>\n<\/div>\n\t<div class=\"swiper-slide\">\n\t<div class=\"wpcp-single-item\">\n\t\t\t<a class=\"wcp-light-box\" data-buttons='[\"close\"]' data-wpc_url='https:\/\/www.fondazioneinvernizzi.it\/wp-content\/uploads\/2026\/03\/200-1536x1090.png' href=\"https:\/\/www.fondazioneinvernizzi.it\/wp-content\/uploads\/2026\/03\/200-1536x1090.png\" data-fancybox=\"wpcp_view\">\n\t\t<figure>\n\t\t\t<img loading=\"lazy\" decoding=\"async\" class=\"skip-lazy\" src=\"https:\/\/www.fondazioneinvernizzi.it\/wp-content\/uploads\/2026\/03\/200-1536x1090.png\" alt=\"200\" width=\"1536\" height=\"1090\">\t\t<\/figure>\n\t<\/a>\n\t\t<\/div>\n<\/div>\n\t<div class=\"swiper-slide\">\n\t<div class=\"wpcp-single-item\">\n\t\t\t<a class=\"wcp-light-box\" data-buttons='[\"close\"]' data-wpc_url='https:\/\/www.fondazioneinvernizzi.it\/wp-content\/uploads\/2026\/03\/201-1536x1090.png' href=\"https:\/\/www.fondazioneinvernizzi.it\/wp-content\/uploads\/2026\/03\/201-1536x1090.png\" data-fancybox=\"wpcp_view\">\n\t\t<figure>\n\t\t\t<img loading=\"lazy\" decoding=\"async\" class=\"skip-lazy\" src=\"https:\/\/www.fondazioneinvernizzi.it\/wp-content\/uploads\/2026\/03\/201-1536x1090.png\" alt=\"201\" width=\"1536\" height=\"1090\">\t\t<\/figure>\n\t<\/a>\n\t\t<\/div>\n<\/div>\n\t<div class=\"swiper-slide\">\n\t<div class=\"wpcp-single-item\">\n\t\t\t<a class=\"wcp-light-box\" data-buttons='[\"close\"]' data-wpc_url='https:\/\/www.fondazioneinvernizzi.it\/wp-content\/uploads\/2026\/03\/202-1536x1090.png' href=\"https:\/\/www.fondazioneinvernizzi.it\/wp-content\/uploads\/2026\/03\/202-1536x1090.png\" data-fancybox=\"wpcp_view\">\n\t\t<figure>\n\t\t\t<img loading=\"lazy\" decoding=\"async\" class=\"skip-lazy\" src=\"https:\/\/www.fondazioneinvernizzi.it\/wp-content\/uploads\/2026\/03\/202-1536x1090.png\" alt=\"202\" width=\"1536\" height=\"1090\">\t\t<\/figure>\n\t<\/a>\n\t\t<\/div>\n<\/div>\n\t<div class=\"swiper-slide\">\n\t<div class=\"wpcp-single-item\">\n\t\t\t<a class=\"wcp-light-box\" data-buttons='[\"close\"]' data-wpc_url='https:\/\/www.fondazioneinvernizzi.it\/wp-content\/uploads\/2026\/03\/203-1536x1090.png' href=\"https:\/\/www.fondazioneinvernizzi.it\/wp-content\/uploads\/2026\/03\/203-1536x1090.png\" data-fancybox=\"wpcp_view\">\n\t\t<figure>\n\t\t\t<img loading=\"lazy\" decoding=\"async\" class=\"skip-lazy\" src=\"https:\/\/www.fondazioneinvernizzi.it\/wp-content\/uploads\/2026\/03\/203-1536x1090.png\" alt=\"203\" width=\"1536\" height=\"1090\">\t\t<\/figure>\n\t<\/a>\n\t\t<\/div>\n<\/div>\n\t<div class=\"swiper-slide\">\n\t<div class=\"wpcp-single-item\">\n\t\t\t<a class=\"wcp-light-box\" data-buttons='[\"close\"]' data-wpc_url='https:\/\/www.fondazioneinvernizzi.it\/wp-content\/uploads\/2026\/03\/204-1536x1090.png' href=\"https:\/\/www.fondazioneinvernizzi.it\/wp-content\/uploads\/2026\/03\/204-1536x1090.png\" data-fancybox=\"wpcp_view\">\n\t\t<figure>\n\t\t\t<img loading=\"lazy\" decoding=\"async\" class=\"skip-lazy\" src=\"https:\/\/www.fondazioneinvernizzi.it\/wp-content\/uploads\/2026\/03\/204-1536x1090.png\" alt=\"204\" width=\"1536\" height=\"1090\">\t\t<\/figure>\n\t<\/a>\n\t\t<\/div>\n<\/div>\n\t<div class=\"swiper-slide\">\n\t<div class=\"wpcp-single-item\">\n\t\t\t<a class=\"wcp-light-box\" data-buttons='[\"close\"]' data-wpc_url='https:\/\/www.fondazioneinvernizzi.it\/wp-content\/uploads\/2026\/03\/210-1536x1090.png' href=\"https:\/\/www.fondazioneinvernizzi.it\/wp-content\/uploads\/2026\/03\/210-1536x1090.png\" data-fancybox=\"wpcp_view\">\n\t\t<figure>\n\t\t\t<img loading=\"lazy\" decoding=\"async\" class=\"skip-lazy\" src=\"https:\/\/www.fondazioneinvernizzi.it\/wp-content\/uploads\/2026\/03\/210-1536x1090.png\" alt=\"210\" width=\"1536\" height=\"1090\">\t\t<\/figure>\n\t<\/a>\n\t\t<\/div>\n<\/div>\n\t<div class=\"swiper-slide\">\n\t<div class=\"wpcp-single-item\">\n\t\t\t<a class=\"wcp-light-box\" data-buttons='[\"close\"]' data-wpc_url='https:\/\/www.fondazioneinvernizzi.it\/wp-content\/uploads\/2026\/03\/205-1536x1090.png' href=\"https:\/\/www.fondazioneinvernizzi.it\/wp-content\/uploads\/2026\/03\/205-1536x1090.png\" data-fancybox=\"wpcp_view\">\n\t\t<figure>\n\t\t\t<img loading=\"lazy\" decoding=\"async\" class=\"skip-lazy\" src=\"https:\/\/www.fondazioneinvernizzi.it\/wp-content\/uploads\/2026\/03\/205-1536x1090.png\" alt=\"205\" width=\"1536\" height=\"1090\">\t\t<\/figure>\n\t<\/a>\n\t\t<\/div>\n<\/div>\n\t<div class=\"swiper-slide\">\n\t<div class=\"wpcp-single-item\">\n\t\t\t<a class=\"wcp-light-box\" data-buttons='[\"close\"]' data-wpc_url='https:\/\/www.fondazioneinvernizzi.it\/wp-content\/uploads\/2026\/03\/211-1536x1090.png' href=\"https:\/\/www.fondazioneinvernizzi.it\/wp-content\/uploads\/2026\/03\/211-1536x1090.png\" data-fancybox=\"wpcp_view\">\n\t\t<figure>\n\t\t\t<img loading=\"lazy\" decoding=\"async\" class=\"skip-lazy\" src=\"https:\/\/www.fondazioneinvernizzi.it\/wp-content\/uploads\/2026\/03\/211-1536x1090.png\" alt=\"211\" width=\"1536\" height=\"1090\">\t\t<\/figure>\n\t<\/a>\n\t\t<\/div>\n<\/div>\n\t<div class=\"swiper-slide\">\n\t<div class=\"wpcp-single-item\">\n\t\t\t<a class=\"wcp-light-box\" data-buttons='[\"close\"]' data-wpc_url='https:\/\/www.fondazioneinvernizzi.it\/wp-content\/uploads\/2026\/03\/206-1536x1090.png' href=\"https:\/\/www.fondazioneinvernizzi.it\/wp-content\/uploads\/2026\/03\/206-1536x1090.png\" data-fancybox=\"wpcp_view\">\n\t\t<figure>\n\t\t\t<img loading=\"lazy\" decoding=\"async\" class=\"skip-lazy\" src=\"https:\/\/www.fondazioneinvernizzi.it\/wp-content\/uploads\/2026\/03\/206-1536x1090.png\" alt=\"206\" width=\"1536\" height=\"1090\">\t\t<\/figure>\n\t<\/a>\n\t\t<\/div>\n<\/div>\n\t<div class=\"swiper-slide\">\n\t<div class=\"wpcp-single-item\">\n\t\t\t<a class=\"wcp-light-box\" data-buttons='[\"close\"]' data-wpc_url='https:\/\/www.fondazioneinvernizzi.it\/wp-content\/uploads\/2026\/03\/207-1536x1090.png' href=\"https:\/\/www.fondazioneinvernizzi.it\/wp-content\/uploads\/2026\/03\/207-1536x1090.png\" data-fancybox=\"wpcp_view\">\n\t\t<figure>\n\t\t\t<img loading=\"lazy\" decoding=\"async\" class=\"skip-lazy\" src=\"https:\/\/www.fondazioneinvernizzi.it\/wp-content\/uploads\/2026\/03\/207-1536x1090.png\" alt=\"207\" width=\"1536\" height=\"1090\">\t\t<\/figure>\n\t<\/a>\n\t\t<\/div>\n<\/div>\n\t<div class=\"swiper-slide\">\n\t<div class=\"wpcp-single-item\">\n\t\t\t<a class=\"wcp-light-box\" data-buttons='[\"close\"]' data-wpc_url='https:\/\/www.fondazioneinvernizzi.it\/wp-content\/uploads\/2026\/03\/209-1536x1090.png' href=\"https:\/\/www.fondazioneinvernizzi.it\/wp-content\/uploads\/2026\/03\/209-1536x1090.png\" data-fancybox=\"wpcp_view\">\n\t\t<figure>\n\t\t\t<img loading=\"lazy\" decoding=\"async\" class=\"skip-lazy\" src=\"https:\/\/www.fondazioneinvernizzi.it\/wp-content\/uploads\/2026\/03\/209-1536x1090.png\" alt=\"209\" width=\"1536\" height=\"1090\">\t\t<\/figure>\n\t<\/a>\n\t\t<\/div>\n<\/div>\n\t<div class=\"swiper-slide\">\n\t<div class=\"wpcp-single-item\">\n\t\t\t<a class=\"wcp-light-box\" data-buttons='[\"close\"]' data-wpc_url='https:\/\/www.fondazioneinvernizzi.it\/wp-content\/uploads\/2026\/03\/208-1536x1090.png' href=\"https:\/\/www.fondazioneinvernizzi.it\/wp-content\/uploads\/2026\/03\/208-1536x1090.png\" data-fancybox=\"wpcp_view\">\n\t\t<figure>\n\t\t\t<img loading=\"lazy\" decoding=\"async\" class=\"skip-lazy\" src=\"https:\/\/www.fondazioneinvernizzi.it\/wp-content\/uploads\/2026\/03\/208-1536x1090.png\" alt=\"208\" width=\"1536\" height=\"1090\">\t\t<\/figure>\n\t<\/a>\n\t\t<\/div>\n<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t<div class=\"wpcp-swiper-dots swiper-pagination\"><\/div>\n\t\t\t\t<!-- If we need navigation buttons -->\n\t\t\t\t\t<div class=\"wpcp-prev-button swiper-button-prev\"><i class=\"fa fa-angle-left\"><\/i><\/div>\n\t\t\t<div class=\"wpcp-next-button swiper-button-next\"><i class=\"fa fa-angle-right\"><\/i><\/div>\n\t\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\n\n\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>Dalla disinformazione alla fiducia: come comunicare scienza e agro-food 24 marzo 2026 &#8211; Strategie e sfide della comunicazione scientifica nel settore agro-alimentare Marted\u00ec 24 marzo alle ore 16.30, Fondazione Invernizzi ha promosso un incontro dedicato al ruolo della comunicazione scientifica nel settore agro-alimentare, con particolare attenzione alle sfide poste dalla disinformazione e dalle fake news. [&hellip;]<\/p>","protected":false},"author":4,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"ngg_post_thumbnail":0,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-2877","post","type-post","status-publish","format-standard","hentry","category-uncategorized"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Dalla disinformazione alla fiducia: come comunicare scienza e agro-food - Fondazione Romeo ed Enrica Invernizzi<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.fondazioneinvernizzi.it\/en\/2026\/03\/24\/dalla-disinformazione-alla-fiducia-come-comunicare-scienza-e-agro-food-in-modo-efficace\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Dalla disinformazione alla fiducia: come comunicare scienza e agro-food - Fondazione Romeo ed Enrica Invernizzi\" \/>\n<meta property=\"og:description\" content=\"Dalla disinformazione alla fiducia: come comunicare scienza e agro-food 24 marzo 2026 &#8211; Strategie e sfide della comunicazione scientifica nel settore agro-alimentare Marted\u00ec 24 marzo alle ore 16.30, Fondazione Invernizzi ha promosso un incontro dedicato al ruolo della comunicazione scientifica nel settore agro-alimentare, con particolare attenzione alle sfide poste dalla disinformazione e dalle fake news. [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.fondazioneinvernizzi.it\/en\/2026\/03\/24\/dalla-disinformazione-alla-fiducia-come-comunicare-scienza-e-agro-food-in-modo-efficace\/\" \/>\n<meta property=\"og:site_name\" content=\"Fondazione Romeo ed Enrica Invernizzi\" \/>\n<meta property=\"article:published_time\" content=\"2026-03-24T10:42:15+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-25T16:13:43+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.fondazioneinvernizzi.it\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-25-at-17.04.56-852x1024.jpeg\" \/>\n<meta name=\"author\" content=\"Alice\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Alice\" \/>\n\t<meta name=\"twitter:label2\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.fondazioneinvernizzi.it\/2026\/03\/24\/dalla-disinformazione-alla-fiducia-come-comunicare-scienza-e-agro-food-in-modo-efficace\/\",\"url\":\"https:\/\/www.fondazioneinvernizzi.it\/2026\/03\/24\/dalla-disinformazione-alla-fiducia-come-comunicare-scienza-e-agro-food-in-modo-efficace\/\",\"name\":\"Dalla disinformazione alla fiducia: come comunicare scienza e agro-food - Fondazione Romeo ed Enrica Invernizzi\",\"isPartOf\":{\"@id\":\"https:\/\/www.fondazioneinvernizzi.it\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.fondazioneinvernizzi.it\/2026\/03\/24\/dalla-disinformazione-alla-fiducia-come-comunicare-scienza-e-agro-food-in-modo-efficace\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.fondazioneinvernizzi.it\/2026\/03\/24\/dalla-disinformazione-alla-fiducia-come-comunicare-scienza-e-agro-food-in-modo-efficace\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.fondazioneinvernizzi.it\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-25-at-17.04.56-852x1024.jpeg\",\"datePublished\":\"2026-03-24T10:42:15+00:00\",\"dateModified\":\"2026-03-25T16:13:43+00:00\",\"author\":{\"@id\":\"https:\/\/www.fondazioneinvernizzi.it\/#\/schema\/person\/bb368e2f1100a6c51c2ebffff27a13f0\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.fondazioneinvernizzi.it\/2026\/03\/24\/dalla-disinformazione-alla-fiducia-come-comunicare-scienza-e-agro-food-in-modo-efficace\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.fondazioneinvernizzi.it\/2026\/03\/24\/dalla-disinformazione-alla-fiducia-come-comunicare-scienza-e-agro-food-in-modo-efficace\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\/\/www.fondazioneinvernizzi.it\/2026\/03\/24\/dalla-disinformazione-alla-fiducia-come-comunicare-scienza-e-agro-food-in-modo-efficace\/#primaryimage\",\"url\":\"https:\/\/www.fondazioneinvernizzi.it\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-25-at-17.04.56-852x1024.jpeg\",\"contentUrl\":\"https:\/\/www.fondazioneinvernizzi.it\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-25-at-17.04.56-852x1024.jpeg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.fondazioneinvernizzi.it\/2026\/03\/24\/dalla-disinformazione-alla-fiducia-come-comunicare-scienza-e-agro-food-in-modo-efficace\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.fondazioneinvernizzi.it\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Dalla disinformazione alla fiducia: come comunicare scienza e agro-food\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.fondazioneinvernizzi.it\/#website\",\"url\":\"https:\/\/www.fondazioneinvernizzi.it\/\",\"name\":\"Fondazione Romeo ed Enrica Invernizzi\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.fondazioneinvernizzi.it\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.fondazioneinvernizzi.it\/#\/schema\/person\/bb368e2f1100a6c51c2ebffff27a13f0\",\"name\":\"Alice\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\/\/www.fondazioneinvernizzi.it\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/f753d2b2998e48bbcd31a780607fe388?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/f753d2b2998e48bbcd31a780607fe388?s=96&d=mm&r=g\",\"caption\":\"Alice\"},\"url\":\"https:\/\/www.fondazioneinvernizzi.it\/en\/author\/alice\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Dalla disinformazione alla fiducia: come comunicare scienza e agro-food - Fondazione Romeo ed Enrica Invernizzi","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.fondazioneinvernizzi.it\/en\/2026\/03\/24\/dalla-disinformazione-alla-fiducia-come-comunicare-scienza-e-agro-food-in-modo-efficace\/","og_locale":"en_GB","og_type":"article","og_title":"Dalla disinformazione alla fiducia: come comunicare scienza e agro-food - Fondazione Romeo ed Enrica Invernizzi","og_description":"Dalla disinformazione alla fiducia: come comunicare scienza e agro-food 24 marzo 2026 &#8211; Strategie e sfide della comunicazione scientifica nel settore agro-alimentare Marted\u00ec 24 marzo alle ore 16.30, Fondazione Invernizzi ha promosso un incontro dedicato al ruolo della comunicazione scientifica nel settore agro-alimentare, con particolare attenzione alle sfide poste dalla disinformazione e dalle fake news. [&hellip;]","og_url":"https:\/\/www.fondazioneinvernizzi.it\/en\/2026\/03\/24\/dalla-disinformazione-alla-fiducia-come-comunicare-scienza-e-agro-food-in-modo-efficace\/","og_site_name":"Fondazione Romeo ed Enrica Invernizzi","article_published_time":"2026-03-24T10:42:15+00:00","article_modified_time":"2026-03-25T16:13:43+00:00","og_image":[{"url":"https:\/\/www.fondazioneinvernizzi.it\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-25-at-17.04.56-852x1024.jpeg"}],"author":"Alice","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Alice","Estimated reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.fondazioneinvernizzi.it\/2026\/03\/24\/dalla-disinformazione-alla-fiducia-come-comunicare-scienza-e-agro-food-in-modo-efficace\/","url":"https:\/\/www.fondazioneinvernizzi.it\/2026\/03\/24\/dalla-disinformazione-alla-fiducia-come-comunicare-scienza-e-agro-food-in-modo-efficace\/","name":"Dalla disinformazione alla fiducia: come comunicare scienza e agro-food - Fondazione Romeo ed Enrica Invernizzi","isPartOf":{"@id":"https:\/\/www.fondazioneinvernizzi.it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.fondazioneinvernizzi.it\/2026\/03\/24\/dalla-disinformazione-alla-fiducia-come-comunicare-scienza-e-agro-food-in-modo-efficace\/#primaryimage"},"image":{"@id":"https:\/\/www.fondazioneinvernizzi.it\/2026\/03\/24\/dalla-disinformazione-alla-fiducia-come-comunicare-scienza-e-agro-food-in-modo-efficace\/#primaryimage"},"thumbnailUrl":"https:\/\/www.fondazioneinvernizzi.it\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-25-at-17.04.56-852x1024.jpeg","datePublished":"2026-03-24T10:42:15+00:00","dateModified":"2026-03-25T16:13:43+00:00","author":{"@id":"https:\/\/www.fondazioneinvernizzi.it\/#\/schema\/person\/bb368e2f1100a6c51c2ebffff27a13f0"},"breadcrumb":{"@id":"https:\/\/www.fondazioneinvernizzi.it\/2026\/03\/24\/dalla-disinformazione-alla-fiducia-come-comunicare-scienza-e-agro-food-in-modo-efficace\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.fondazioneinvernizzi.it\/2026\/03\/24\/dalla-disinformazione-alla-fiducia-come-comunicare-scienza-e-agro-food-in-modo-efficace\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/www.fondazioneinvernizzi.it\/2026\/03\/24\/dalla-disinformazione-alla-fiducia-come-comunicare-scienza-e-agro-food-in-modo-efficace\/#primaryimage","url":"https:\/\/www.fondazioneinvernizzi.it\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-25-at-17.04.56-852x1024.jpeg","contentUrl":"https:\/\/www.fondazioneinvernizzi.it\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-25-at-17.04.56-852x1024.jpeg"},{"@type":"BreadcrumbList","@id":"https:\/\/www.fondazioneinvernizzi.it\/2026\/03\/24\/dalla-disinformazione-alla-fiducia-come-comunicare-scienza-e-agro-food-in-modo-efficace\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.fondazioneinvernizzi.it\/"},{"@type":"ListItem","position":2,"name":"Dalla disinformazione alla fiducia: come comunicare scienza e agro-food"}]},{"@type":"WebSite","@id":"https:\/\/www.fondazioneinvernizzi.it\/#website","url":"https:\/\/www.fondazioneinvernizzi.it\/","name":"Fondazione Romeo ed Enrica Invernizzi","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.fondazioneinvernizzi.it\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-GB"},{"@type":"Person","@id":"https:\/\/www.fondazioneinvernizzi.it\/#\/schema\/person\/bb368e2f1100a6c51c2ebffff27a13f0","name":"Alice","image":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/www.fondazioneinvernizzi.it\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/f753d2b2998e48bbcd31a780607fe388?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f753d2b2998e48bbcd31a780607fe388?s=96&d=mm&r=g","caption":"Alice"},"url":"https:\/\/www.fondazioneinvernizzi.it\/en\/author\/alice\/"}]}},"post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/www.fondazioneinvernizzi.it\/en\/wp-json\/wp\/v2\/posts\/2877","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fondazioneinvernizzi.it\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fondazioneinvernizzi.it\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fondazioneinvernizzi.it\/en\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fondazioneinvernizzi.it\/en\/wp-json\/wp\/v2\/comments?post=2877"}],"version-history":[{"count":15,"href":"https:\/\/www.fondazioneinvernizzi.it\/en\/wp-json\/wp\/v2\/posts\/2877\/revisions"}],"predecessor-version":[{"id":2973,"href":"https:\/\/www.fondazioneinvernizzi.it\/en\/wp-json\/wp\/v2\/posts\/2877\/revisions\/2973"}],"wp:attachment":[{"href":"https:\/\/www.fondazioneinvernizzi.it\/en\/wp-json\/wp\/v2\/media?parent=2877"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fondazioneinvernizzi.it\/en\/wp-json\/wp\/v2\/categories?post=2877"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fondazioneinvernizzi.it\/en\/wp-json\/wp\/v2\/tags?post=2877"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}